{"id":8,"count":3,"description":"","link":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/","name":"Alemanha","slug":"alemanha","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ViajandoFeliz.com.br - Dicas de viagem<\/title>\n<meta name=\"description\" content=\"Dicas de Viagem, Roteiros de viagem para europa e Am\u00e9rica Latina.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ViajandoFeliz.com.br - Dicas de viagem\" \/>\n<meta property=\"og:description\" content=\"Dicas de Viagem, Roteiros de viagem para europa e Am\u00e9rica Latina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicas de Viagem - Viajando Feliz\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/tag\\\/alemanha\\\/\",\"url\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/tag\\\/alemanha\\\/\",\"name\":\"ViajandoFeliz.com.br - Dicas de viagem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/#website\"},\"description\":\"Dicas de Viagem, Roteiros de viagem para europa e Am\u00e9rica Latina.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/tag\\\/alemanha\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/tag\\\/alemanha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alemanha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/#website\",\"url\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/\",\"name\":\"Dicas de Viagem - Viajando Feliz\",\"description\":\"Dicas de Viagem, Roteiros e Relatos de viagens\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/viajandofeliz.com.br\\\/viagens\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ViajandoFeliz.com.br - Dicas de viagem","description":"Dicas de Viagem, Roteiros de viagem para europa e Am\u00e9rica Latina.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/","og_locale":"pt_BR","og_type":"article","og_title":"ViajandoFeliz.com.br - Dicas de viagem","og_description":"Dicas de Viagem, Roteiros de viagem para europa e Am\u00e9rica Latina.","og_url":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/","og_site_name":"Dicas de Viagem - Viajando Feliz","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/","url":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/","name":"ViajandoFeliz.com.br - Dicas de viagem","isPartOf":{"@id":"https:\/\/viajandofeliz.com.br\/viagens\/#website"},"description":"Dicas de Viagem, Roteiros de viagem para europa e Am\u00e9rica Latina.","breadcrumb":{"@id":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/viajandofeliz.com.br\/viagens\/tag\/alemanha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/viajandofeliz.com.br\/viagens\/"},{"@type":"ListItem","position":2,"name":"Alemanha"}]},{"@type":"WebSite","@id":"https:\/\/viajandofeliz.com.br\/viagens\/#website","url":"https:\/\/viajandofeliz.com.br\/viagens\/","name":"Dicas de Viagem - Viajando Feliz","description":"Dicas de Viagem, Roteiros e Relatos de viagens","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/viajandofeliz.com.br\/viagens\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/viajandofeliz.com.br\/viagens\/wp-json\/wp\/v2\/tags\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viajandofeliz.com.br\/viagens\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/viajandofeliz.com.br\/viagens\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/viajandofeliz.com.br\/viagens\/wp-json\/wp\/v2\/posts?tags=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}